{"id":3886,"date":"2022-04-19T10:01:21","date_gmt":"2022-04-19T08:01:21","guid":{"rendered":"http:\/\/www.vfl-fluorn-fussball.de\/wordpress\/?p=3886"},"modified":"2022-04-19T10:37:18","modified_gmt":"2022-04-19T08:37:18","slug":"spielberichte-der-sgms-vom-16-04-22","status":"publish","type":"post","link":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/","title":{"rendered":"Spielberichte der SGMs vom 16.04.22"},"content":{"rendered":"<p><strong>SGM Fluorn-Winzeln I &#8211; SV Herrenzimmern 1:1 (1:1)<\/strong><\/p>\n<p>Im Spiel unserer Mannschaft gegen den SV Herrenzimmern, das bei zun\u00e4chst eher ungem\u00fctlichem, weil windigem und k\u00fchlem Wetter begann, wurde von keiner der beiden Seiten spielerisch hohes Niveau geboten.<br \/>\nDa half es auch nicht, dass der \u00e4u\u00dferst pingelige Schiedsrichter jeglichen Spielfluss durch angebliche Fouls, die Fragezeichen bei beiden Mannschaften hervorriefen, im Keim erstickte.<br \/>\nDurch die 1:0-F\u00fchrung, die die G\u00e4ste in der 31. Minute in Form eines Freisto\u00dfes erzielten, wurde die SGM aber nicht unruhig und konnte gl\u00fccklicherweise noch kurz vor dem Halbzeitpfiff den Ausgleichstreffer durch Lars Merz erzielen.<br \/>\nZwar wurde es nach und nach sonnig, doch durch die immer noch recht windigen Verh\u00e4ltnisse wurden dann vor allem in der zweiten Halbzeit viele Flanken und lange B\u00e4lle ins Aus getragen, wo sie keinen Abnehmer fanden. Weiterhin war kein Spielfluss gegeben, da nahezu jeder Zweikampf oder K\u00f6rperkontakt ein Foul zur Folge hatte.<br \/>\nSo trudelte das Spiel vor sich hin, allerdings ohne spielerischen Glanz oder wirklich eindeutige Torchancen f\u00fcr eine der Mannschaften.<br \/>\nAuch aus dem Platzverweis in Form einer gelb-roten Karte seitens der Herrenzimmerner, der bei 7 gelben Karten im Spiel und den fragw\u00fcrdigen und willk\u00fcrlichen Schiedsrichterentscheidungen nur eine Frage der Zeit war, konnte unsere Mannschaft in der Nachspielzeit keinen Profit mehr schlagen.<br \/>\nSo ging die Punkteteilung weitestgehend in Ordnung, auch wenn mit etwas Gl\u00fcck ein Sieg herausspringen h\u00e4tte k\u00f6nnen.<br \/>\nMit Blick auf das Spiel gegen den Tabellenf\u00fchrer Hardt am kommenden Mittwoch steht unserem Team allerdings voraussichtlich kein leichteres Spiel bevor.<\/p>\n<p><strong>FC Suebia Rottweil III &#8211; SGM Fluorn-Winzeln II 5:2 (2:1)<\/strong><br \/>\nUm mindestens zwei Tore zu hoch fiel die Niederlage am vergangenen Ostersamstag gegen die Sueben aus Rottweil aus.<br \/>\nDabei pr\u00e4sentierte man sich trotz gro\u00dfer Personalsorgen gegen einen starken Gegner &#8211; die Sueben hatten in der Vorwoche gegen den Tabellenf\u00fchrer aus Bochingen sportlich mit 5:0 gewonnen, nachtr\u00e4glich am gr\u00fcnen Tisch aber eine 0:3-Wertung kassiert &#8211; wirklich gut. K\u00e4mpferisch und l\u00e4uferisch war man ohnehin wieder gut eingestellt, zeigte aber auch immer wieder spielerisch \u00fcberraschend gute Akzente. So entwickelte sich ein offenes Spiel auf hohem Niveau. Leider nutzten die Sueben die Chancen, die unsere Elf zun\u00e4chst fahrl\u00e4ssig liegen lie\u00df und ging bis zur 40. Spielminute mit 2:0 in F\u00fchrung. Psychologisch wichtig war dann, dass Alex Sauer noch mit dem Halbzeitpfiff den 2:1 Anschlusstreffer erzielen konnte. Auff\u00e4llig war in diesem Spiel auch, dass man so viele vielversprechende Standardsituationen aus 16-25 Metern vor dem Tor zugesprochen bekam, wie lange nicht mehr. Leider konnte man keine davon nutzen und der beste direkte Freisto\u00df von Alex Sauer etwa Mitte der zweiten Spielh\u00e4lfte verfehlte sein Ziel nur knapp, w\u00e4hrend die allermeisten anderen ihr Ziel weit verfehlten. Bei direkten Freist\u00f6\u00dfen ist also noch viel Luft nach oben.<br \/>\nNach dem Seitentausch waren die Sueben fr\u00fch bem\u00fcht das Spiel zu entscheiden und machten offensiv ziemlich viel Druck. Das gab uns auf der anderen Seite mehr Platz f\u00fcr Konter nach Ballgewinnen im Mittelfeld. Nachdem Sascha Schneider gleich mehrere Zweik\u00e4mpfe gewann, setzte er Manu Graf im Anschluss gut in Szene. Der drang in den Gegnerischen Sechzehner ein, sah den am langen Pfosten mitgelaufenen Alex Sauer, welcher den Konter blitzsauber zum 2:2 Ausgleich abschlie\u00dfen konnte. Nur kurz darauf vergab Maikail Akyildiz die gro\u00dfe Chance zur 3:2 F\u00fchrung. Eine Flanke nahm er v\u00f6llig freistehend &#8211; er h\u00e4tte den Ball wohl auch noch annehmen k\u00f6nnen &#8211; direkt aus acht Metern, verzog dann aber doch deutlich. Danach zeigten die Offensivbem\u00fchungen der Rottweiler, dann aber doch Wirkung und man kassierte das 3:2. Manu Graf hatte nach einem Schnittstellenball noch die Chance zum Ausgleich, der Torh\u00fcter war beim Steilpass aber vor ihm zur Stelle. W\u00e4re das Spiel nach 80. Minuten mit 3:2 oder eben 3:3 abgepfiffen worden, h\u00e4tte man von einem leistungsgerechten Ergebnis sprechen k\u00f6nnen. Leider kamen dann noch die letzten zehn Minuten, in denen man der kraftraubenden Partie Tribut zollen musste und dabei aber auch unn\u00f6tige Fehler produzierte. So wurde aus einer wirklich ordentlichen Leistung in einem ausgeglichenen Spiel am Ende eine auf dem Papier doch eher herbe Niederlage. Schade, aber auch daran kann man in der Zukunft noch arbeiten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SGM Fluorn-Winzeln I &#8211; SV Herrenzimmern 1:1 (1:1) Im Spiel unserer Mannschaft gegen den SV Herrenzimmern, das bei zun\u00e4chst eher ungem\u00fctlichem, weil windigem und k\u00fchlem Wetter begann, wurde von keiner der beiden Seiten spielerisch hohes Niveau geboten. Da half es auch nicht, dass der \u00e4u\u00dferst pingelige Schiedsrichter jeglichen Spielfluss durch angebliche Fouls, die Fragezeichen bei beiden Mannschaften hervorriefen, im Keim erstickte. Durch die 1:0-F\u00fchrung, die die G\u00e4ste in der 31. Minute in Form eines Freisto\u00dfes erzielten, wurde die SGM aber nicht unruhig und konnte gl\u00fccklicherweise noch kurz vor dem Halbzeitpfiff den Ausgleichstreffer durch Lars Merz erzielen. Zwar wurde es nach und nach sonnig, doch durch die immer noch recht windigen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3],"tags":[],"class_list":["post-3886","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-spielberichte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spielberichte der SGMs vom 16.04.22 - VfL Fluorn Fu\u00dfball 1924 e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spielberichte der SGMs vom 16.04.22 - VfL Fluorn Fu\u00dfball 1924 e.V.\" \/>\n<meta property=\"og:description\" content=\"SGM Fluorn-Winzeln I &#8211; SV Herrenzimmern 1:1 (1:1) Im Spiel unserer Mannschaft gegen den SV Herrenzimmern, das bei zun\u00e4chst eher ungem\u00fctlichem, weil windigem und k\u00fchlem Wetter begann, wurde von keiner der beiden Seiten spielerisch hohes Niveau geboten. Da half es auch nicht, dass der \u00e4u\u00dferst pingelige Schiedsrichter jeglichen Spielfluss durch angebliche Fouls, die Fragezeichen bei beiden Mannschaften hervorriefen, im Keim erstickte. Durch die 1:0-F\u00fchrung, die die G\u00e4ste in der 31. Minute in Form eines Freisto\u00dfes erzielten, wurde die SGM aber nicht unruhig und konnte gl\u00fccklicherweise noch kurz vor dem Halbzeitpfiff den Ausgleichstreffer durch Lars Merz erzielen. Zwar wurde es nach und nach sonnig, doch durch die immer noch recht windigen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/\" \/>\n<meta property=\"og:site_name\" content=\"VfL Fluorn Fu\u00dfball 1924 e.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/p\/Vfl-Fluorn-1924-eV-100036848576053\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-19T08:01:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-19T08:37:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-content\/uploads\/2023\/12\/HeaderWMSponsors4_final-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ankaufma\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"ankaufma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/spielberichte-der-sgms-vom-16-04-22\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/spielberichte-der-sgms-vom-16-04-22\\\/\"},\"author\":{\"name\":\"ankaufma\",\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/3af506b0fa18f0ab2d3369072c2ff93c\"},\"headline\":\"Spielberichte der SGMs vom 16.04.22\",\"datePublished\":\"2022-04-19T08:01:21+00:00\",\"dateModified\":\"2022-04-19T08:37:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/spielberichte-der-sgms-vom-16-04-22\\\/\"},\"wordCount\":704,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/#organization\"},\"articleSection\":{\"1\":\"Spielberichte\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/spielberichte-der-sgms-vom-16-04-22\\\/\",\"url\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/spielberichte-der-sgms-vom-16-04-22\\\/\",\"name\":\"Spielberichte der SGMs vom 16.04.22 - VfL Fluorn Fu\u00dfball 1924 e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/#website\"},\"datePublished\":\"2022-04-19T08:01:21+00:00\",\"dateModified\":\"2022-04-19T08:37:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/spielberichte-der-sgms-vom-16-04-22\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/spielberichte-der-sgms-vom-16-04-22\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/spielberichte-der-sgms-vom-16-04-22\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spielberichte der SGMs vom 16.04.22\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/\",\"name\":\"VfL Fluorn Fu\u00dfball 1924 e.V.\",\"description\":\"Mein Freund ist aus Leder\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/#organization\",\"name\":\"VfL Fluorn Fu\u00dfball 1924 e.V.\",\"url\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/VfLLogoOhneHintergrund.png\",\"contentUrl\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/VfLLogoOhneHintergrund.png\",\"width\":963,\"height\":963,\"caption\":\"VfL Fluorn Fu\u00dfball 1924 e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/de-de.facebook.com\\\/p\\\/Vfl-Fluorn-1924-eV-100036848576053\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/#\\\/schema\\\/person\\\/3af506b0fa18f0ab2d3369072c2ff93c\",\"name\":\"ankaufma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94b25ff5a2ca5bbb66c0f23cf4a2b2599aef9c8365f849d3270fd622c2a0ac17?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94b25ff5a2ca5bbb66c0f23cf4a2b2599aef9c8365f849d3270fd622c2a0ac17?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94b25ff5a2ca5bbb66c0f23cf4a2b2599aef9c8365f849d3270fd622c2a0ac17?s=96&d=mm&r=g\",\"caption\":\"ankaufma\"},\"url\":\"https:\\\/\\\/www.vfl-fluorn-fussball.de\\\/wordpress\\\/author\\\/ankaufma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spielberichte der SGMs vom 16.04.22 - VfL Fluorn Fu\u00dfball 1924 e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/","og_locale":"de_DE","og_type":"article","og_title":"Spielberichte der SGMs vom 16.04.22 - VfL Fluorn Fu\u00dfball 1924 e.V.","og_description":"SGM Fluorn-Winzeln I &#8211; SV Herrenzimmern 1:1 (1:1) Im Spiel unserer Mannschaft gegen den SV Herrenzimmern, das bei zun\u00e4chst eher ungem\u00fctlichem, weil windigem und k\u00fchlem Wetter begann, wurde von keiner der beiden Seiten spielerisch hohes Niveau geboten. Da half es auch nicht, dass der \u00e4u\u00dferst pingelige Schiedsrichter jeglichen Spielfluss durch angebliche Fouls, die Fragezeichen bei beiden Mannschaften hervorriefen, im Keim erstickte. Durch die 1:0-F\u00fchrung, die die G\u00e4ste in der 31. Minute in Form eines Freisto\u00dfes erzielten, wurde die SGM aber nicht unruhig und konnte gl\u00fccklicherweise noch kurz vor dem Halbzeitpfiff den Ausgleichstreffer durch Lars Merz erzielen. Zwar wurde es nach und nach sonnig, doch durch die immer noch recht windigen [&hellip;]","og_url":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/","og_site_name":"VfL Fluorn Fu\u00dfball 1924 e.V.","article_publisher":"https:\/\/de-de.facebook.com\/p\/Vfl-Fluorn-1924-eV-100036848576053\/","article_published_time":"2022-04-19T08:01:21+00:00","article_modified_time":"2022-04-19T08:37:18+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-content\/uploads\/2023\/12\/HeaderWMSponsors4_final-1024x576.png","type":"image\/png"}],"author":"ankaufma","twitter_misc":{"Verfasst von":"ankaufma","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/#article","isPartOf":{"@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/"},"author":{"name":"ankaufma","@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/#\/schema\/person\/3af506b0fa18f0ab2d3369072c2ff93c"},"headline":"Spielberichte der SGMs vom 16.04.22","datePublished":"2022-04-19T08:01:21+00:00","dateModified":"2022-04-19T08:37:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/"},"wordCount":704,"publisher":{"@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/#organization"},"articleSection":{"1":"Spielberichte"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/","url":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/","name":"Spielberichte der SGMs vom 16.04.22 - VfL Fluorn Fu\u00dfball 1924 e.V.","isPartOf":{"@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/#website"},"datePublished":"2022-04-19T08:01:21+00:00","dateModified":"2022-04-19T08:37:18+00:00","breadcrumb":{"@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/spielberichte-der-sgms-vom-16-04-22\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Spielberichte der SGMs vom 16.04.22"}]},{"@type":"WebSite","@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/#website","url":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/","name":"VfL Fluorn Fu\u00dfball 1924 e.V.","description":"Mein Freund ist aus Leder","publisher":{"@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/#organization","name":"VfL Fluorn Fu\u00dfball 1924 e.V.","url":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-content\/uploads\/2023\/12\/VfLLogoOhneHintergrund.png","contentUrl":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-content\/uploads\/2023\/12\/VfLLogoOhneHintergrund.png","width":963,"height":963,"caption":"VfL Fluorn Fu\u00dfball 1924 e.V."},"image":{"@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/p\/Vfl-Fluorn-1924-eV-100036848576053\/"]},{"@type":"Person","@id":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/#\/schema\/person\/3af506b0fa18f0ab2d3369072c2ff93c","name":"ankaufma","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/94b25ff5a2ca5bbb66c0f23cf4a2b2599aef9c8365f849d3270fd622c2a0ac17?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94b25ff5a2ca5bbb66c0f23cf4a2b2599aef9c8365f849d3270fd622c2a0ac17?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94b25ff5a2ca5bbb66c0f23cf4a2b2599aef9c8365f849d3270fd622c2a0ac17?s=96&d=mm&r=g","caption":"ankaufma"},"url":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/author\/ankaufma\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/posts\/3886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/comments?post=3886"}],"version-history":[{"count":4,"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/posts\/3886\/revisions"}],"predecessor-version":[{"id":3897,"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/posts\/3886\/revisions\/3897"}],"wp:attachment":[{"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/media?parent=3886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/categories?post=3886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vfl-fluorn-fussball.de\/wordpress\/wp-json\/wp\/v2\/tags?post=3886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}